{"id":115576,"date":"2026-03-13T19:16:25","date_gmt":"2026-03-13T17:16:25","guid":{"rendered":"https:\/\/granada.salesianos.edu\/colegio\/?p=115576"},"modified":"2026-03-24T19:16:50","modified_gmt":"2026-03-24T17:16:50","slug":"bachillerato-presente-en-las-olimpiadas-de-fisica","status":"publish","type":"post","link":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/","title":{"rendered":"Bachillerato presente en las Olimpiadas de F\u00edsica"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb _builder_version=\u00bb4.27.4&#8243; global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.5&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"flex flex-col text-sm pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:81395b40-21a9-4cf5-ac5e-7d1612d5cef6-0\" data-testid=\"conversation-turn-2\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] @w-sm\/main:[--thread-content-margin:--spacing(6)] @w-lg\/main:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"ef8efefe-5bd6-4378-b3fa-0365426a825d\" data-message-model-slug=\"gpt-5-2\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p>El Bachillerato Tecnol\u00f3gico nos vuelve a llenar de orgullo, un a\u00f1o m\u00e1s, en las Olimpiadas de F\u00edsica<\/p>\n<p>Tres alumnos representaron a nuestro centro en la fase local celebrada el pasado viernes, demostrando esfuerzo, talento y unos valores que nos hacen sentir especialmente orgullosos.<\/p>\n<p>El pasado viernes se celebr\u00f3 la fase local de las Olimpiadas de F\u00edsica y desde el colegio queremos felicitar a nuestros tres alumnos participantes.<\/p>\n<p>Los tres han demostrado un enorme esfuerzo, dedicaci\u00f3n y pasi\u00f3n por la ciencia, representando a nuestro centro con trabajo, ilusi\u00f3n y una actitud ejemplar.<\/p>\n<p>Adem\u00e1s, dos de ellos consiguieron situarse entre los diez primeros clasificados de Granada, un magn\u00edfico resultado.<\/p>\n<p>Pero m\u00e1s all\u00e1 de las posiciones obtenidas, queremos destacar algo a\u00fan m\u00e1s importante: el esfuerzo, la constancia y la calidad humana de los tres. Son un verdadero orgullo para nuestro colegio.<\/p>\n<p>Recibid la felicitaci\u00f3n de toda la comunidad educativa y, de forma muy especial, la de su profesora, profundamente orgullosa de su trabajo y de las personas en las que se est\u00e1n convirtiendo.<\/p>\n<p>\u00a1Felicidades a los tres!<\/p>\n<p>#olimpiadasfisica #fisica #salesianosesciencia<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\">\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Bachillerato Tecnol\u00f3gico nos vuelve a llenar de orgullo, un a\u00f1o m\u00e1s, en las Olimpiadas de F\u00edsica<\/p>\n","protected":false},"author":2,"featured_media":115577,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[30,57,11],"tags":[],"class_list":["post-115576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artes","category-bachillerato","category-colegio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bachillerato presente en las Olimpiadas de F\u00edsica - Colegio Salesiano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bachillerato presente en las Olimpiadas de F\u00edsica - Colegio Salesiano\" \/>\n<meta property=\"og:description\" content=\"El Bachillerato Tecnol\u00f3gico nos vuelve a llenar de orgullo, un a\u00f1o m\u00e1s, en las Olimpiadas de F\u00edsica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/\" \/>\n<meta property=\"og:site_name\" content=\"Colegio Salesiano\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SalesianosGR\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-13T17:16:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T17:16:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1918\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GranadaSDB\" \/>\n<meta name=\"twitter:site\" content=\"@GranadaSDB\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/6392ff2e4bd1e66981d6eab734bbd962\"},\"headline\":\"Bachillerato presente en las Olimpiadas de F\u00edsica\",\"datePublished\":\"2026-03-13T17:16:25+00:00\",\"dateModified\":\"2026-03-24T17:16:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg\",\"articleSection\":[\"Artes\",\"Bachillerato\",\"Colegio\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/\",\"name\":\"Bachillerato presente en las Olimpiadas de F\u00edsica - Colegio Salesiano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg\",\"datePublished\":\"2026-03-13T17:16:25+00:00\",\"dateModified\":\"2026-03-24T17:16:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg\",\"contentUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg\",\"width\":1440,\"height\":1918},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/blog\\\/bachillerato-presente-en-las-olimpiadas-de-fisica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bachillerato presente en las Olimpiadas de F\u00edsica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#website\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/\",\"name\":\"Colegio Salesiano\",\"description\":\"P\u00e1gina oficial de Salesianos Granada San Juan Bosco\",\"publisher\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#organization\",\"name\":\"Colegio Salesiano San Juan Bosco Granada\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/GRANADAobraVN2.jpg\",\"contentUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/01\\\/GRANADAobraVN2.jpg\",\"width\":2113,\"height\":1894,\"caption\":\"Colegio Salesiano San Juan Bosco Granada\"},\"image\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SalesianosGR\\\/\",\"https:\\\/\\\/x.com\\\/GranadaSDB\",\"https:\\\/\\\/www.instagram.com\\\/salesianosgranada\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UChkpZuhCf4Y5rYIcFT3CNxw?view_as=subscriber\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/colegio\\\/#\\\/schema\\\/person\\\/6392ff2e4bd1e66981d6eab734bbd962\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bachillerato presente en las Olimpiadas de F\u00edsica - Colegio Salesiano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/","og_locale":"es_ES","og_type":"article","og_title":"Bachillerato presente en las Olimpiadas de F\u00edsica - Colegio Salesiano","og_description":"El Bachillerato Tecnol\u00f3gico nos vuelve a llenar de orgullo, un a\u00f1o m\u00e1s, en las Olimpiadas de F\u00edsica","og_url":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/","og_site_name":"Colegio Salesiano","article_publisher":"https:\/\/www.facebook.com\/SalesianosGR\/","article_published_time":"2026-03-13T17:16:25+00:00","article_modified_time":"2026-03-24T17:16:50+00:00","og_image":[{"width":1440,"height":1918,"url":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_creator":"@GranadaSDB","twitter_site":"@GranadaSDB","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#article","isPartOf":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/"},"author":{"name":"Gestor Web","@id":"https:\/\/granada.salesianos.edu\/colegio\/#\/schema\/person\/6392ff2e4bd1e66981d6eab734bbd962"},"headline":"Bachillerato presente en las Olimpiadas de F\u00edsica","datePublished":"2026-03-13T17:16:25+00:00","dateModified":"2026-03-24T17:16:50+00:00","mainEntityOfPage":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/#organization"},"image":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#primaryimage"},"thumbnailUrl":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg","articleSection":["Artes","Bachillerato","Colegio"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/","url":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/","name":"Bachillerato presente en las Olimpiadas de F\u00edsica - Colegio Salesiano","isPartOf":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/#website"},"primaryImageOfPage":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#primaryimage"},"image":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#primaryimage"},"thumbnailUrl":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg","datePublished":"2026-03-13T17:16:25+00:00","dateModified":"2026-03-24T17:16:50+00:00","breadcrumb":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#primaryimage","url":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg","contentUrl":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2026\/03\/WhatsApp-Image-2026-03-24-at-18.01.34.jpeg","width":1440,"height":1918},{"@type":"BreadcrumbList","@id":"https:\/\/granada.salesianos.edu\/colegio\/blog\/bachillerato-presente-en-las-olimpiadas-de-fisica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/granada.salesianos.edu\/colegio\/"},{"@type":"ListItem","position":2,"name":"Bachillerato presente en las Olimpiadas de F\u00edsica"}]},{"@type":"WebSite","@id":"https:\/\/granada.salesianos.edu\/colegio\/#website","url":"https:\/\/granada.salesianos.edu\/colegio\/","name":"Colegio Salesiano","description":"P\u00e1gina oficial de Salesianos Granada San Juan Bosco","publisher":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granada.salesianos.edu\/colegio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/granada.salesianos.edu\/colegio\/#organization","name":"Colegio Salesiano San Juan Bosco Granada","url":"https:\/\/granada.salesianos.edu\/colegio\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/granada.salesianos.edu\/colegio\/#\/schema\/logo\/image\/","url":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/GRANADAobraVN2.jpg","contentUrl":"https:\/\/granada.salesianos.edu\/colegio\/wp-content\/uploads\/sites\/2\/2021\/01\/GRANADAobraVN2.jpg","width":2113,"height":1894,"caption":"Colegio Salesiano San Juan Bosco Granada"},"image":{"@id":"https:\/\/granada.salesianos.edu\/colegio\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SalesianosGR\/","https:\/\/x.com\/GranadaSDB","https:\/\/www.instagram.com\/salesianosgranada\/","https:\/\/www.youtube.com\/channel\/UChkpZuhCf4Y5rYIcFT3CNxw?view_as=subscriber"]},{"@type":"Person","@id":"https:\/\/granada.salesianos.edu\/colegio\/#\/schema\/person\/6392ff2e4bd1e66981d6eab734bbd962","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/115576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/comments?post=115576"}],"version-history":[{"count":2,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/115576\/revisions"}],"predecessor-version":[{"id":115586,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/posts\/115576\/revisions\/115586"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media\/115577"}],"wp:attachment":[{"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/media?parent=115576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/categories?post=115576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.salesianos.edu\/colegio\/wp-json\/wp\/v2\/tags?post=115576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}