{"id":7167,"date":"2018-01-25T11:55:12","date_gmt":"2018-01-25T09:55:12","guid":{"rendered":"https:\/\/granada.salesianos.edu\/familiasalesiana\/?p=7167"},"modified":"2018-01-25T12:00:31","modified_gmt":"2018-01-25T10:00:31","slug":"varias-actividades-de-bachillerato-y-ciclos","status":"publish","type":"post","link":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/","title":{"rendered":"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS"},"content":{"rendered":"<div id=\"fb-root\"><\/div>\n<p>[et_pb_section bb_built=\u00bb1&#8243; admin_label=\u00bbsection\u00bb][et_pb_row admin_label=\u00bbrow\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb background_size=\u00bbinitial\u00bb][et_pb_column type=\u00bb4_4&#8243;][et_pb_text admin_label=\u00bbEntradilla (Texto)\u00bb _builder_version=\u00bb3.0.92&#8243; background_layout=\u00bblight\u00bb text_orientation=\u00bbjustified\u00bb text_font=\u00bb|on|||\u00bb]<\/p>\n<h3><strong><span style=\"color: #ff0000;\">Drones, Cultura Emprendedora y TG7 marcan momentos especiales para los alumnos de Bachillerato y Ciclos<\/span><\/strong><\/h3>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbAutor (Texto)\u00bb _builder_version=\u00bb3.0.92&#8243; background_layout=\u00bblight\u00bb text_font=\u00bb||on||\u00bb]<\/p>\n<p>Por: Profesores de Bachillerato y CCFF<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbDesarrollo (Texto)\u00bb _builder_version=\u00bb3.0.92&#8243; background_layout=\u00bblight\u00bb text_orientation=\u00bbjustified\u00bb]<\/p>\n<p><strong>1.- Alumnos de 1BH, en la asignatura Cultura Emprendedora<\/strong> y Empresarial.Taller de Emprendimiento con M\u00f3nica Martos, T\u00e9cnica del CADE de Armilla (Centro de Emprendedores de Andaluc\u00eda).<img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-7169 alignleft\" src=\"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-300x225.jpeg 300w, https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-768x576.jpeg 768w, https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-1024x768.jpeg 1024w, https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-510x382.jpeg 510w, https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-1080x810.jpeg 1080w, https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg 1600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: left;\"><strong>2.- Los alumnos de primer curso de Realizaci\u00f3n de Proyectos Audiovisuales<\/strong> y Espect\u00e1culos han recibido por parte de Francisco Olmedo de la empresa CurroGo, una Master Class sobre el uso, manejo y legislaci\u00f3n de los Drones. La master class ha contado con una parte pr\u00e1ctica en los patios del colegio. Francisco Olmedo es antiguo alumno del ciclo.<\/p>\n<p style=\"text-align: left;\"><strong>3.-\u00a0Los alumnos de segundo curso de Realizaci\u00f3n de Proyectos Audiovisuales y Espect\u00e1culos<\/strong> acompa\u00f1ados por su tutor han visitado las instalaciones de la televisi\u00f3n local TG7. Han sido atendidos por el Jefe T\u00e9cnico Jos\u00e9 Antonio Callejas, antiguo alumno de nuestro colegio. La visita ha sido de gran inter\u00e9s para los alumnos, ya que adem\u00e1s supone una empresa en la que realizan la formaci\u00f3n en centros de trabajo.<\/p>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00bbT\u00edtulo: Galer\u00eda de fotos (Texto)\u00bb _builder_version=\u00bb3.0.92&#8243; background_layout=\u00bblight\u00bb text_font=\u00bb|on|||\u00bb text_text_color=\u00bb#dc001b\u00bb disabled=\u00bbon\u00bb disabled_on=\u00bbon|on|on\u00bb]<\/p>\n<p>GALER\u00cdA FOTOGR\u00c1FICA<\/p>\n<p>[Best_Wordpress_Gallery id=\u00bb6&#8243; gal_title=\u00bbNAVIDAD SOLIDARIA\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][et_pb_gallery _builder_version=\u00bb3.0.92&#8243; posts_number=\u00bb8&#8243; show_title_and_caption=\u00bboff\u00bb show_pagination=\u00bbon\u00bb fullwidth=\u00bboff\u00bb orientation=\u00bblandscape\u00bb zoom_icon_color=\u00bb#dc001b\u00bb hover_overlay_color=\u00bbrgba(255,255,255,0.9)\u00bb hover_icon=\u00bb%%51%%\u00bb background_layout=\u00bblight\u00bb border_style=\u00bbsolid\u00bb auto=\u00bboff\u00bb disabled=\u00bbon\u00bb disabled_on=\u00bbon|on|on\u00bb \/][et_pb_video _builder_version=\u00bb3.0.51&#8243; disabled=\u00bbon\u00bb disabled_on=\u00bbon|on|on\u00bb \/][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de primer curso de Realizaci\u00f3n de Proyectos Audiovisuales y Espect\u00e1culos han recibido por parte de Francisco Olmedo de la empresa CurroGo, una Master Class sobre el uso, manejo y legislaci\u00f3n de los Drones. La master class ha contado con una parte pr\u00e1ctica en los patios del colegio. Francisco Olmedo es antiguo alumno del ciclo.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[11,10,1],"tags":[],"class_list":["post-7167","post","type-post","status-publish","format-standard","hentry","category-colegio","category-portada","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS - Familia Salesiana<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS - Familia Salesiana\" \/>\n<meta property=\"og:description\" content=\"Los alumnos de primer curso de Realizaci\u00f3n de Proyectos Audiovisuales y Espect\u00e1culos han recibido por parte de Francisco Olmedo de la empresa CurroGo, una Master Class sobre el uso, manejo y legislaci\u00f3n de los Drones. La master class ha contado con una parte pr\u00e1ctica en los patios del colegio. Francisco Olmedo es antiguo alumno del ciclo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/\" \/>\n<meta property=\"og:site_name\" content=\"Familia Salesiana\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-25T09:55:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-25T10:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gestor Web\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gestor Web\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/\"},\"author\":{\"name\":\"Gestor Web\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/6392ff2e4bd1e66981d6eab734bbd962\"},\"headline\":\"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS\",\"datePublished\":\"2018-01-25T09:55:12+00:00\",\"dateModified\":\"2018-01-25T10:00:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/\"},\"wordCount\":392,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/01\\\/WhatsApp-Image-2018-01-23-at-22.06.29-1-300x225.jpeg\",\"articleSection\":[\"Colegio\",\"Portada\",\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/\",\"name\":\"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS - Familia Salesiana\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/01\\\/WhatsApp-Image-2018-01-23-at-22.06.29-1-300x225.jpeg\",\"datePublished\":\"2018-01-25T09:55:12+00:00\",\"dateModified\":\"2018-01-25T10:00:31+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/6392ff2e4bd1e66981d6eab734bbd962\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/01\\\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/wp-content\\\/uploads\\\/sites\\\/8\\\/2018\\\/01\\\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/blog\\\/varias-actividades-de-bachillerato-y-ciclos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/#website\",\"url\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/\",\"name\":\"Familia Salesiana\",\"description\":\"P\u00e1gina oficial de Salesianos Granada San Juan Bosco\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/granada.salesianos.edu\\\/familiasalesiana\\\/#\\\/schema\\\/person\\\/6392ff2e4bd1e66981d6eab734bbd962\",\"name\":\"Gestor Web\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g\",\"caption\":\"Gestor Web\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS - Familia Salesiana","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/","og_locale":"es_ES","og_type":"article","og_title":"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS - Familia Salesiana","og_description":"Los alumnos de primer curso de Realizaci\u00f3n de Proyectos Audiovisuales y Espect\u00e1culos han recibido por parte de Francisco Olmedo de la empresa CurroGo, una Master Class sobre el uso, manejo y legislaci\u00f3n de los Drones. La master class ha contado con una parte pr\u00e1ctica en los patios del colegio. Francisco Olmedo es antiguo alumno del ciclo.","og_url":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/","og_site_name":"Familia Salesiana","article_published_time":"2018-01-25T09:55:12+00:00","article_modified_time":"2018-01-25T10:00:31+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg","type":"image\/jpeg"}],"author":"Gestor Web","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gestor Web","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#article","isPartOf":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/"},"author":{"name":"Gestor Web","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/#\/schema\/person\/6392ff2e4bd1e66981d6eab734bbd962"},"headline":"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS","datePublished":"2018-01-25T09:55:12+00:00","dateModified":"2018-01-25T10:00:31+00:00","mainEntityOfPage":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/"},"wordCount":392,"commentCount":0,"image":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#primaryimage"},"thumbnailUrl":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-300x225.jpeg","articleSection":["Colegio","Portada","Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/","url":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/","name":"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS - Familia Salesiana","isPartOf":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/#website"},"primaryImageOfPage":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#primaryimage"},"image":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#primaryimage"},"thumbnailUrl":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1-300x225.jpeg","datePublished":"2018-01-25T09:55:12+00:00","dateModified":"2018-01-25T10:00:31+00:00","author":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/#\/schema\/person\/6392ff2e4bd1e66981d6eab734bbd962"},"breadcrumb":{"@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#primaryimage","url":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg","contentUrl":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-content\/uploads\/sites\/8\/2018\/01\/WhatsApp-Image-2018-01-23-at-22.06.29-1.jpeg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/blog\/varias-actividades-de-bachillerato-y-ciclos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/granada.salesianos.edu\/familiasalesiana\/"},{"@type":"ListItem","position":2,"name":"VARIAS ACTIVIDADES DE BACHILLERATO Y CICLOS"}]},{"@type":"WebSite","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/#website","url":"https:\/\/granada.salesianos.edu\/familiasalesiana\/","name":"Familia Salesiana","description":"P\u00e1gina oficial de Salesianos Granada San Juan Bosco","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/granada.salesianos.edu\/familiasalesiana\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/granada.salesianos.edu\/familiasalesiana\/#\/schema\/person\/6392ff2e4bd1e66981d6eab734bbd962","name":"Gestor Web","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/160666bb56a01520857079961a824af2b7821d6bad80677c80f2b473fceead1b?s=96&d=mm&r=g","caption":"Gestor Web"}}]}},"_links":{"self":[{"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/7167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/comments?post=7167"}],"version-history":[{"count":2,"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/7167\/revisions"}],"predecessor-version":[{"id":7171,"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/posts\/7167\/revisions\/7171"}],"wp:attachment":[{"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/media?parent=7167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/categories?post=7167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/granada.salesianos.edu\/familiasalesiana\/wp-json\/wp\/v2\/tags?post=7167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}